{"id":856,"count":2,"description":"","link":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/","name":"mcgregor","slug":"mcgregor","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>mcgregor Archives - Travelstart Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mcgregor Archives - Travelstart Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/\" \/>\n<meta property=\"og:site_name\" content=\"Travelstart Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/tag\\\/mcgregor\\\/\",\"url\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/tag\\\/mcgregor\\\/\",\"name\":\"mcgregor Archives - Travelstart Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/tag\\\/mcgregor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/tag\\\/mcgregor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mcgregor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/\",\"name\":\"Travelstart Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/#organization\",\"name\":\"Travelstart Blog\",\"url\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/08\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/08\\\/logo.svg\",\"width\":147,\"height\":35,\"caption\":\"Travelstart Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.travelstart.co.za\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"mcgregor Archives - Travelstart Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/","og_locale":"en_US","og_type":"article","og_title":"mcgregor Archives - Travelstart Blog","og_url":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/","og_site_name":"Travelstart Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/","url":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/","name":"mcgregor Archives - Travelstart Blog","isPartOf":{"@id":"https:\/\/www.travelstart.co.za\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.travelstart.co.za\/blog\/tag\/mcgregor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.travelstart.co.za\/blog\/"},{"@type":"ListItem","position":2,"name":"mcgregor"}]},{"@type":"WebSite","@id":"https:\/\/www.travelstart.co.za\/blog\/#website","url":"https:\/\/www.travelstart.co.za\/blog\/","name":"Travelstart Blog","description":"","publisher":{"@id":"https:\/\/www.travelstart.co.za\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.travelstart.co.za\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.travelstart.co.za\/blog\/#organization","name":"Travelstart Blog","url":"https:\/\/www.travelstart.co.za\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.travelstart.co.za\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.travelstart.co.za\/blog\/wp-content\/uploads\/sites\/5\/2025\/08\/logo.svg","contentUrl":"https:\/\/www.travelstart.co.za\/blog\/wp-content\/uploads\/sites\/5\/2025\/08\/logo.svg","width":147,"height":35,"caption":"Travelstart Blog"},"image":{"@id":"https:\/\/www.travelstart.co.za\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.travelstart.co.za\/blog\/wp-json\/wp\/v2\/tags\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.travelstart.co.za\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.travelstart.co.za\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.travelstart.co.za\/blog\/wp-json\/wp\/v2\/posts?tags=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}